{"id":22,"count":3,"description":"","link":"https:\/\/mvermeulen.org\/gone2look4america\/category\/massachusetts\/","name":"Massachusetts","slug":"massachusetts","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/mvermeulen.org\/gone2look4america\/wp-json\/wp\/v2\/categories\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mvermeulen.org\/gone2look4america\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mvermeulen.org\/gone2look4america\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mvermeulen.org\/gone2look4america\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}