{"id":61,"count":23,"description":"","link":"https:\/\/mvermeulen.org\/gone2look4america\/tag\/capitol\/","name":"Capitol","slug":"capitol","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/mvermeulen.org\/gone2look4america\/wp-json\/wp\/v2\/tags\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mvermeulen.org\/gone2look4america\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mvermeulen.org\/gone2look4america\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mvermeulen.org\/gone2look4america\/wp-json\/wp\/v2\/posts?tags=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}